{"id":89,"count":245,"description":"","link":"https:\/\/renodoll.com\/sl\/brand\/wm-doll\/","name":"WM Doll","slug":"wm-doll","taxonomy":"brand","parent":0,"meta":{"thumbnail_id":["63119"],"_trp_automatically_translated_slug_it_IT":["wm-bambola"],"_trp_automatically_translated_slug_fr_FR":["wm-poupee"],"_trp_automatically_translated_slug_es_ES":["muneca-wm"],"_trp_automatically_translated_slug_nl_NL":["wm-pop"],"_trp_automatically_translated_slug_de_DE":["wm-puppe"],"_aioseo_title":[null],"_aioseo_description":[null],"_aioseo_keywords":[""],"_aioseo_og_title":[null],"_aioseo_og_description":[null],"_aioseo_og_article_section":[""],"_aioseo_og_article_tags":[""],"_aioseo_twitter_title":[null],"_aioseo_twitter_description":[null],"_trp_automatically_translated_slug_fi":["wm-nukke"],"_trp_automatically_translated_slug_cs_CZ":["wm-panenka"],"_trp_automatically_translated_slug_sv_SE":["wm-docka"],"_trp_automatically_translated_slug_pl_PL":["wm-lalka"],"_trp_automatically_translated_slug_hu_HU":["wm-baba"],"_trp_automatically_translated_slug_et":["wm-nukk"],"_trp_automatically_translated_slug_hr":["wm-lutka"],"_trp_automatically_translated_slug_ro_RO":["wm-papusa"],"_trp_automatically_translated_slug_sl_SI":["wm-lutka"],"_trp_automatically_translated_slug_bg_BG":["wm-%d0%ba%d1%83%d0%ba%d0%bb%d0%b0"],"_trp_automatically_translated_slug_pt_PT":["boneca-wm"],"_trp_automatically_translated_slug_lt_LT":["wm-lele"],"_trp_automatically_translated_slug_sk_SK":["wm-babika"],"_trp_automatically_translated_slug_lv":["wm-lelle"],"_trp_automatically_translated_slug_da_DK":["wm-dukke"],"_trp_automatically_translated_slug_el":["wm-%ce%ba%ce%bf%cf%8d%ce%ba%ce%bb%ce%b1"],"_trp_automatically_translated_slug_nb_NO":["wm-dukke"]},"image":{"id":["63119"],"src":"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-wm.jpg","alt":[],"title":"logo-wm","caption":"#image_title","description":"#image_title"},"_links":{"self":[{"href":"https:\/\/renodoll.com\/sl\/wp-json\/wp\/v2\/etheme_brands\/89","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/renodoll.com\/sl\/wp-json\/wp\/v2\/etheme_brands"}],"about":[{"href":"https:\/\/renodoll.com\/sl\/wp-json\/wp\/v2\/taxonomies\/brand"}],"wp:post_type":[{"href":"https:\/\/renodoll.com\/sl\/wp-json\/wp\/v2\/product?etheme_brands=89"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}