{"id":71829,"date":"2024-11-30T07:54:54","date_gmt":"2024-11-29T23:54:54","guid":{"rendered":"https:\/\/renodoll.com\/?post_type=product&#038;p=71829"},"modified":"2024-12-09T02:10:35","modified_gmt":"2024-12-08T18:10:35","slug":"fanfic-adrien-ladybug-sex-doll","status":"publish","type":"product","link":"https:\/\/renodoll.com\/ro\/products\/fanfic-adrien-ladybug-sex-doll\/","title":{"rendered":"P\u0103pu\u0219a sexual\u0103 Adrien Ladybug Starla 159cm - Fanfic"},"content":{"rendered":"<div class=\"product_desc_section\">\n<h3 style=\"text-align: left;\"><strong>Galeria P\u0103pu\u0219ilor<\/strong><\/h3>\n<div class=\"doll_gallery_section\">\t                <ul class=\"easy-image-gallery thumbnails-25 linked\">\r\n                    <li><a data-fancybox=\"gallery945\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p1.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p1-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p1-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p1-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery945\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p2-1.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p2-1-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p2-1-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p2-1-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery945\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p3.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p3-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p3-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p3-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery945\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p4.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p4-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p4-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p4-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery945\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p5.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p5-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p5-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p5-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery945\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p6.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p6-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p6-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p6-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery945\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p7.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p7-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p7-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p7-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery945\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p8.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p8-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p8-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p8-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery945\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p9.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p9-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p9-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p9-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery945\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p10.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p10-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p10-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p10-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery945\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p11.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p11-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p11-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p11-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery945\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p12.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p12-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p12-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p12-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery945\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p13.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p13-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p13-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p13-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery945\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p14.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p14-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p14-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p14-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery945\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p15.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p15-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p15-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p15-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery945\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p16.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p16-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p16-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p16-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery945\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p17.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p17-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p17-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p17-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery945\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p18.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p18-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p18-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p18-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery945\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p19.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p19-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p19-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p19-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery945\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p20.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p20-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p20-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p20-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery945\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p21.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p21-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p21-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p21-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery945\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p22.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p22-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p22-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p22-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery945\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p23.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p23-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p23-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p23-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery945\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p24.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p24-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p24-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p24-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery945\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p25.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p25-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p25-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2024\/11\/sex-women-doll-cOr23p25-100x100.jpg 100w\" \/><\/a><\/li><\/ul><\/div>\n<div class=\"clear_both\"><\/div>\n<div class=\"product_desc_col1\">\n<h3 style=\"text-align: left;\"><strong>Dimensiunile p\u0103pu\u0219ii<\/strong><\/h3>\n<table width=\"363\">\n<tbody>\n<tr>\n<td width=\"130\">Material<\/td>\n<td width=\"233\">Cap din silicon + corp TPE<\/td>\n<\/tr>\n<tr>\n<td>\u00cen\u0103l\u0163ime<\/td>\n<td>159 cm<\/td>\n<\/tr>\n<tr>\n<td>Linia s\u00e2nilor<\/td>\n<td>82 cm<\/td>\n<\/tr>\n<tr>\n<td>Linia taliei<\/td>\n<td>53 cm<\/td>\n<\/tr>\n<tr>\n<td>Linia \u0219oldului<\/td>\n<td>94 cm<\/td>\n<\/tr>\n<tr>\n<td>Lungimea bra\u021bului<\/td>\n<td>66 cm<\/td>\n<\/tr>\n<tr>\n<td>L\u0103\u021bimea um\u0103rului<\/td>\n<td>33 cm<\/td>\n<\/tr>\n<tr>\n<td>Linia vi\u021belului<\/td>\n<td>31 cm<\/td>\n<\/tr>\n<tr>\n<td>Linia coapsei<\/td>\n<td>51 cm<\/td>\n<\/tr>\n<tr>\n<td>Lungimea piciorului<\/td>\n<td>85 cm<\/td>\n<\/tr>\n<tr>\n<td>Dimensiunea picioarelor<\/td>\n<td>21 cm<\/td>\n<\/tr>\n<tr>\n<td>Greutate net\u0103<\/td>\n<td>37 kg<\/td>\n<\/tr>\n<tr>\n<td>Ad\u00e2ncimea vaginului<\/td>\n<td>18 cm<\/td>\n<\/tr>\n<tr>\n<td>Ad\u00e2ncimea anal\u0103<\/td>\n<td>16 cm<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<div class=\"product_desc_col1\">\n<h3><strong>Despre Papusa<\/strong><\/h3>\n\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"16236\" class=\"elementor elementor-16236\" data-elementor-post-type=\"staticblocks\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-75eb1f80 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"75eb1f80\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-70392c7b\" data-id=\"70392c7b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b8ce90 elementor-widget elementor-widget-text-editor\" data-id=\"7b8ce90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>De-a lungul anilor, am livrat multe p\u0103pu\u0219i sexuale de calitate \u0219i eficiente. Serviciile noastre ofer\u0103 o satisfac\u021bie pe care cineva s-ar crede c\u0103 este dincolo de posibil. Produsele noastre sunt bune 100%, iar sistemul nostru de plat\u0103 este flexibil, cu un sistem de garantare a ramburs\u0103rii banilor pentru p\u0103pu\u0219ile noastre sexuale.<\/li><li>P\u0103pu\u0219ile noastre realiste de dragoste vin \u00een toate nuan\u021bele la pre\u021buri accesibile, livrare excelent\u0103 a produselor, care este f\u0103r\u0103 stres \u0219i flexibil\u0103.<\/li><li>Produsele RenoDoll pot fi verificate pe toate forumurile de p\u0103pu\u0219i. Ne l\u0103ud\u0103m cu recenzii excelente \u0219i \u00eencurajatoare despre produse, cu o evaluare \u0219i recenzii de cinci stele de top \u0219i nici cu o singur\u0103 recenzie negativ\u0103, care v\u0103 asigur\u0103 \u00een continuare calitatea maxim\u0103 care vine cu produsele noastre.<\/li><li>Suntem o echipa extrem de eficienta. Cheltuielile noastre generale sunt mici, ceea ce v\u0103 ajut\u0103 s\u0103 cheltui\u021bi mai pu\u021bin pe p\u0103pu\u0219i sexuale de calitate atunci c\u00e2nd cump\u0103ra\u021bi de la noi.<\/li><li>De asemenea, ne l\u0103ud\u0103m cu un serviciu remarcabil client-produc\u0103tor. Echipa noastr\u0103 de ajutor este \u00eentotdeauna gata s\u0103 asculte \u0219i s\u0103 ofere ceea ce este necesar \u0219i s\u0103 lucreze la feedback-ul clien\u021bilor no\u0219tri. Clien\u021bii no\u0219tri sunt prioritatea noastr\u0103 principal\u0103 \u0219i muncim din greu pentru a ne asigura c\u0103 fiecare client este mul\u021bumit \u0219i prime\u0219te tot ce merit\u0103.<\/li><\/ul><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\n<\/div>\n<div class=\"clear_both\"><\/div>\n<div class=\"product_desc_row\">\n<h3 style=\"text-align: left;\"><strong>Mai multe informatii<\/strong><\/h3>\n\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"5107\" class=\"elementor elementor-5107\" data-elementor-post-type=\"staticblocks\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f4da12a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f4da12a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d6a2412\" data-id=\"d6a2412\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e7bba8 elementor-widget-divider--view-line_text elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"7e7bba8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<h3 class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\tSpectacol de schelete de la WM Dolls\t\t\t\t<\/h3>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-abc0118 elementor-widget elementor-widget-image\" data-id=\"abc0118\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"693\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/elementor\/thumbs\/xstore-placeholder-q1lsnz7fehkm1srdmxtn5lk7se7rj04saxv7z16xig.png\" class=\"attachment-full size-full wp-image-63174 lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/06\/pages-skeleton-1.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/06\/pages-skeleton-1.jpg 1500w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/06\/pages-skeleton-1-300x139.jpg 300w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/06\/pages-skeleton-1-1024x473.jpg 1024w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/06\/pages-skeleton-1-768x355.jpg 768w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/06\/pages-skeleton-1-18x8.jpg 18w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/06\/pages-skeleton-1-100x46.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/06\/pages-skeleton-1-600x277.jpg 600w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/06\/pages-skeleton-1-10x5.jpg 10w\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5cff75b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5cff75b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4952662\" data-id=\"4952662\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac8a6d7 elementor-widget-divider--view-line_text elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"ac8a6d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<h3 class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\tBaza de cuno\u0219tin\u021be pentru p\u0103pu\u0219i sexuale\t\t\t\t<\/h3>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-80290db elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"80290db\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-942d32c\" data-id=\"942d32c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f528340 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"f528340\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/ro\/automatic-sex-doll\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> Papusa sexuala automata<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/ro\/auto-blowjob-sex-doll\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Papusa sexuala cu muie automata<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/ro\/electric-hip-sex-doll\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">P\u0103pu\u0219\u0103 electric\u0103 pentru \u0219old<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/ro\/articulated-finger\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Deget articulat<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/ro\/evo-yoga-skeleton\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Scheletul EVO Yoga<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/ro\/what-is-a-sex-doll\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Ce este o p\u0103pu\u0219\u0103 sexual\u0103?<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/ro\/sex-doll-care\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00cengrijirea p\u0103pu\u0219ilor sexuale<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b322228\" data-id=\"b322228\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c591da9 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"c591da9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/ro\/sex-doll-dress-up\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Dress Up pentru p\u0103pu\u0219i sexuale<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/ro\/sex-doll-skeleton\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Schelet de p\u0103pu\u0219\u0103 sexual\u0103<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/ro\/sex-doll-breast-options\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Op\u021biuni pentru s\u00e2ni pentru p\u0103pu\u0219i sexuale<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/ro\/heating-system\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> Sistem de incalzire<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/ro\/sex-doll-moaning\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">P\u0103pu\u0219\u0103 sexual\u0103 Gemet\u0103<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/ro\/sex-doll-tongue\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Limba p\u0103pu\u0219ilor sexuale<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-f9e8f13\" data-id=\"f9e8f13\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51a1c15 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"51a1c15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/ro\/blood-vessel\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Vas de s\u00e2nge<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/ro\/sex-doll-maintenance\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00centre\u021binere p\u0103pu\u0219i sexuale<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/ro\/movement-range\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Interval de mi\u0219care<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/ro\/standing-without-bolts\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Stand f\u0103r\u0103 \u0219uruburi<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/ro\/freckles\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Pictura cu pistrui<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/ro\/sex-doll-storage\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Depozitare p\u0103pu\u0219i sexuale<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-854f952 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"854f952\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ec5780d\" data-id=\"ec5780d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a107d79 elementor-widget-divider--view-line_text elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"a107d79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<h3 class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\tCele mai bune m\u0103rci de p\u0103pu\u0219i sexuale\t\t\t\t<\/h3>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9aa171a elementor-widget elementor-widget-etheme_brands\" data-id=\"9aa171a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"etheme_brands.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <link rel=\"stylesheet\" href=\"https:\/\/renodoll.com\/wp-content\/themes\/xstore\/css\/modules\/woocommerce\/brands-carousel.min.css?ver=0.0.1\" type=\"text\/css\" media=\"all\" \/> \t\t\n            <div class=\"swiper-entry brands-carousel middle arrows-hover\">\n\n                <div class=\"swiper-container  brands-carousel-1982 stop-on-hover\" data-breakpoints=\"1\" data-xs-slides=\"1\" data-sm-slides=\"2\" data-md-slides=\"7\" data-lt-slides=\"7\" data-slides-per-view=\"7\" data-space=\"30\" data-autoplay=\"3000\" data-slides-per-group=\"1\" data-speed=\"300\" data-loop=\"true\">\n\n                    <div class=\"swiper-wrapper\">\n\n\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/ro\/brand\/6ye-doll\/\" title=\"Papusa 6YE\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-6ye.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-6ye.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-6ye-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-6ye-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-6ye-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/ro\/brand\/angelkiss-doll\/\" title=\"P\u0103pu\u0219\u0103 AngelKiss\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-angelkiss.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-angelkiss.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-angelkiss-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-angelkiss-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-angelkiss-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/ro\/brand\/as-doll\/\" title=\"AS Doll\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-asdoll.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-asdoll.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-asdoll-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-asdoll-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-asdoll-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/ro\/brand\/dh-doll\/\" title=\"Papusa DH\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-dh.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-dh.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-dh-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-dh-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-dh-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/ro\/brand\/elsababe-doll\/\" title=\"P\u0103pu\u0219a Elsababe\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-elsababe.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-elsababe.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-elsababe-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-elsababe-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-elsababe-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/ro\/brand\/fj-doll\/\" title=\"P\u0103pu\u0219\u0103 FJ\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-fj.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-fj.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-fj-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-fj-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-fj-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/ro\/brand\/gamelady-doll\/\" title=\"Joc Lady Doll\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-gamelady.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-gamelady.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-gamelady-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-gamelady-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-gamelady-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/ro\/brand\/hr-doll\/\" title=\"P\u0103pu\u0219\u0103 HR\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-hrdoll.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-hrdoll.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-hrdoll-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-hrdoll-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-hrdoll-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/ro\/brand\/irontech-doll\/\" title=\"P\u0103pu\u0219\u0103 Irontech\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-irontechdoll.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-irontechdoll.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-irontechdoll-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-irontechdoll-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-irontechdoll-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/ro\/brand\/jarliet-doll\/\" title=\"Papusa Jarliet\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-jarliet.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-jarliet.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-jarliet-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-jarliet-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-jarliet-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/ro\/brand\/jinsan-doll\/\" title=\"Papusa Jinsan\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-jinsan.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-jinsan.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-jinsan-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-jinsan-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-jinsan-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/ro\/brand\/or-doll\/\" title=\"SAU P\u0103pu\u0219\u0103\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-or.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-or.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-or-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-or-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-or-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/ro\/brand\/se-doll\/\" title=\"P\u0103pu\u0219\u0103 SE\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-se.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-se.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-se-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-se-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-se-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/ro\/brand\/wm-doll\/\" title=\"Papusa WM\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-wm.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-wm.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-wm-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-wm-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-wm-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/ro\/brand\/yl-doll\/\" title=\"Papusa YL\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-yl.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-yl.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-yl-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-yl-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-yl-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/ro\/brand\/zelex-doll\/\" title=\"P\u0103pu\u0219\u0103 Zelex\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-zelex.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-zelex.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-zelex-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-zelex-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-zelex-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                    <\/div>\n\t\t\t\t\t\n                <\/div>\n\n\t\t\t\t\n                    <div class=\"swiper-button-prev swiper-custom-left swiper-nav et-swiper-elementor-nav type-arrow style-2\"><\/div>\n                    <div class=\"swiper-button-next swiper-custom-right swiper-nav et-swiper-elementor-nav type-arrow style-2\"><\/div>\n\n\t\t\t\t\t\t\t\t\t            <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Galerie de p\u0103pu\u0219i Dimensiuni p\u0103pu\u0219\u0103 Material Cap silicon + TPE \u00cen\u0103l\u021bime corp 159cm Linia s\u00e2nilor 82cm Linia taliei 53cm Linia \u0219oldurilor 94cm Lungime bra\u021b 66cm L\u0103\u021bimea umerilor 33cm Linia gambei 31cm Linia coapselor 51cm Lungime picior 85cm Dimensiune picioare 21cm Greutate net\u0103 37kg Ad\u00e2ncime vagin 18cm Ad\u00e2ncime anal\u0103 16cm Despre p\u0103pu\u0219\u0103 Mai multe informa\u021bii<\/p>","protected":false},"featured_media":71858,"comment_status":"open","ping_status":"closed","template":"","meta":[],"etheme_brands":[],"product_brand":[],"product_cat":[64,113,117,29,26,106,50,68],"product_tag":[],"class_list":{"0":"post-71829","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-150cm-159cm","7":"product_cat-113","8":"product_cat-36kg-40kg","9":"product_cat-asian-sex-doll","10":"product_cat-big-boobs-sex-doll","11":"product_cat-nude-sex-doll","12":"product_cat-silicon-head-tpe-body","13":"product_cat-skinny-sex-doll","14":"tm-has-options","16":"first","17":"instock","18":"sale","19":"shipping-taxable","20":"purchasable","21":"product-type-simple"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/renodoll.com\/ro\/wp-json\/wp\/v2\/product\/71829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/renodoll.com\/ro\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/renodoll.com\/ro\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/renodoll.com\/ro\/wp-json\/wp\/v2\/comments?post=71829"}],"version-history":[{"count":1,"href":"https:\/\/renodoll.com\/ro\/wp-json\/wp\/v2\/product\/71829\/revisions"}],"predecessor-version":[{"id":72081,"href":"https:\/\/renodoll.com\/ro\/wp-json\/wp\/v2\/product\/71829\/revisions\/72081"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/renodoll.com\/ro\/wp-json\/wp\/v2\/media\/71858"}],"wp:attachment":[{"href":"https:\/\/renodoll.com\/ro\/wp-json\/wp\/v2\/media?parent=71829"}],"wp:term":[{"taxonomy":"brand","embeddable":true,"href":"https:\/\/renodoll.com\/ro\/wp-json\/wp\/v2\/etheme_brands?post=71829"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/renodoll.com\/ro\/wp-json\/wp\/v2\/product_brand?post=71829"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/renodoll.com\/ro\/wp-json\/wp\/v2\/product_cat?post=71829"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/renodoll.com\/ro\/wp-json\/wp\/v2\/product_tag?post=71829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}