{"id":10267,"date":"2023-03-19T03:47:37","date_gmt":"2023-03-18T19:47:37","guid":{"rendered":"https:\/\/renodoll.com\/?post_type=product&#038;p=10267"},"modified":"2023-09-08T07:09:18","modified_gmt":"2023-09-07T23:09:18","slug":"ultimate-sexual-real-life-size-dolls","status":"publish","type":"product","link":"https:\/\/renodoll.com\/pt\/products\/ultimate-sexual-real-life-size-dolls\/","title":{"rendered":"Bonecas Ultimate Sexuais em tamanho real Jodie 165 cm"},"content":{"rendered":"<div class=\"product_desc_section\">\n<h3 style=\"text-align: left;\"><strong>Galeria de Bonecas<\/strong><\/h3>\n<div class=\"doll_gallery_section\">\t                <ul class=\"easy-image-gallery thumbnails-14 linked\">\r\n                    <li><a data-fancybox=\"gallery246\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v2.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v2-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v2-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v2-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery246\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v3.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v3-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v3-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v3-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery246\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v4.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v4-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v4-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v4-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery246\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v5.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v5-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v5-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v5-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery246\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v6.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v6-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v6-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v6-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery246\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v7.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v7-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v7-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v7-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery246\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v8.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v8-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v8-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v8-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery246\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v9.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v9-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v9-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v9-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery246\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v10.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v10-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v10-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v10-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery246\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v11.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v11-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v11-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v11-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery246\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v12.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v12-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v12-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v12-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery246\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v13.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v13-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v13-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v13-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery246\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v14.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v14-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v14-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v14-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery246\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v15.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v15-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v15-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/creation-dolls-s6v15-100x100.jpg 100w\" \/><\/a><\/li><\/ul><\/div>\n<div class=\"clear_both\"><\/div>\n<div class=\"product_desc_col1\">\n<h3 style=\"text-align: left;\"><strong>Dimens\u00f5es da boneca<\/strong><\/h3>\n<table width=\"269\">\n<tbody>\n<tr>\n<td width=\"130\">Material<\/td>\n<td width=\"139\">TPE<\/td>\n<\/tr>\n<tr>\n<td>Altura<\/td>\n<td>165cm<\/td>\n<\/tr>\n<tr>\n<td>Seios<\/td>\n<td>87cm<\/td>\n<\/tr>\n<tr>\n<td>Cintura<\/td>\n<td>58cm<\/td>\n<\/tr>\n<tr>\n<td>Quadril<\/td>\n<td>88cm<\/td>\n<\/tr>\n<tr>\n<td>Peso l\u00edquido<\/td>\n<td>36KG<\/td>\n<\/tr>\n<tr>\n<td>Profundidade Oral<\/td>\n<td>13cm<\/td>\n<\/tr>\n<tr>\n<td>Profundidade Vaginal<\/td>\n<td>17cm<\/td>\n<\/tr>\n<tr>\n<td>Profundidade Anal<\/td>\n<td>16cm<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<div class=\"product_desc_col1\">\n<h3><strong>Sobre a boneca<\/strong><\/h3>\n<p>Apresentando bonecas sexuais reais \u2013 a companhia perfeita para homens! Nossas bonecas anatomicamente corretas em tamanho real s\u00e3o projetadas para proporcionar a melhor experi\u00eancia de prazer. Feitas com materiais de silicone TPE da mais alta qualidade, essas bonecas s\u00e3o projetadas para parecer e se sentir como uma mulher de verdade. Com caracter\u00edsticas e formas corporais realistas, essas bonecas proporcionam uma experi\u00eancia sexual realista. Para maior conveni\u00eancia, essas bonecas podem at\u00e9 ser infladas para uma experi\u00eancia mais confort\u00e1vel. Quer voc\u00ea esteja procurando uma experi\u00eancia de prazer \u00fanica ou uma companheira de longo prazo, as bonecas sexuais em tamanho real s\u00e3o a escolha perfeita.<\/p>\n<p>A experi\u00eancia sexual realista que essas bonecas da vida real proporcionam ao cliente \u00e9 algo nunca antes feito no mercado de bonecas sexuais.<\/p>\n<p>Especialmente com suas caracter\u00edsticas anatomicamente corretas que tornam mais f\u00e1cil para qualquer usu\u00e1rio ter uma sensa\u00e7\u00e3o de uma experi\u00eancia sexual com uma mulher muito sexy e bonita como uma boneca sexual. As bonecas sexuais Zoe s\u00e3o a escolha perfeita para a maioria dos homens quando se trata disso, tendo caracter\u00edsticas ador\u00e1veis que acredito que todo usu\u00e1rio deseja ao considerar comprar uma boneca sexual.<\/p>\n<p>Se voc\u00ea quer a melhor experi\u00eancia sexual com uma boneca sexual, ent\u00e3o a boneca sexual Zoe \u00e9 o lugar perfeito para comprar.<\/p>\n<\/div>\n<div class=\"clear_both\"><\/div>\n<div class=\"product_desc_row\">\n<h3 style=\"text-align: left;\"><strong>Mais informa\u00e7\u00f5es<\/strong><\/h3>\n\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"5107\" class=\"elementor elementor-5107\" data-elementor-post-type=\"staticblocks\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f4da12a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f4da12a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d6a2412\" data-id=\"d6a2412\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e7bba8 elementor-widget-divider--view-line_text elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"7e7bba8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<h3 class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\tShow de esqueletos das bonecas WM\t\t\t\t<\/h3>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-abc0118 elementor-widget elementor-widget-image\" data-id=\"abc0118\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"693\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/elementor\/thumbs\/xstore-placeholder-q1lsnz7fehkm1srdmxtn5lk7se7rj04saxv7z16xig.png\" class=\"attachment-full size-full wp-image-63174 lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/06\/pages-skeleton-1.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/06\/pages-skeleton-1.jpg 1500w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/06\/pages-skeleton-1-300x139.jpg 300w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/06\/pages-skeleton-1-1024x473.jpg 1024w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/06\/pages-skeleton-1-768x355.jpg 768w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/06\/pages-skeleton-1-18x8.jpg 18w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/06\/pages-skeleton-1-100x46.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/06\/pages-skeleton-1-600x277.jpg 600w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/06\/pages-skeleton-1-10x5.jpg 10w\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5cff75b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5cff75b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4952662\" data-id=\"4952662\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac8a6d7 elementor-widget-divider--view-line_text elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"ac8a6d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<h3 class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\tBase de conhecimento de bonecas sexuais\t\t\t\t<\/h3>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-80290db elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"80290db\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-942d32c\" data-id=\"942d32c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f528340 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"f528340\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/pt\/automatic-sex-doll\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> Boneca Sexual Autom\u00e1tica<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/pt\/auto-blowjob-sex-doll\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Boneca sexual com boquete autom\u00e1tico<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/pt\/electric-hip-sex-doll\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Boneca sexual el\u00e9trica de quadril<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/pt\/articulated-finger\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Dedo Articulado<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/pt\/evo-yoga-skeleton\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Esqueleto de ioga EVO<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/pt\/what-is-a-sex-doll\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">O que \u00e9 uma boneca sexual?<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/pt\/sex-doll-care\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Cuidados com bonecas sexuais<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b322228\" data-id=\"b322228\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c591da9 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"c591da9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/pt\/sex-doll-dress-up\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Vestir boneca sexual<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/pt\/sex-doll-skeleton\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Esqueleto de boneca sexual<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/pt\/sex-doll-breast-options\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Op\u00e7\u00f5es de seios de bonecas sexuais<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/pt\/heating-system\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> Aquecedor<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/pt\/sex-doll-moaning\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Boneca Sexual Gemendo<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/pt\/sex-doll-tongue\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">L\u00edngua de boneca sexual<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-f9e8f13\" data-id=\"f9e8f13\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51a1c15 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"51a1c15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/pt\/blood-vessel\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Vaso sangu\u00edneo<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/pt\/sex-doll-maintenance\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Manuten\u00e7\u00e3o de bonecas sexuais<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/pt\/movement-range\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Faixa de movimento<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/pt\/standing-without-bolts\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Em p\u00e9 sem parafusos<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/pt\/freckles\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Pintura de Sardas<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/pt\/sex-doll-storage\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Armazenamento de bonecas sexuais<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-854f952 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"854f952\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ec5780d\" data-id=\"ec5780d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a107d79 elementor-widget-divider--view-line_text elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"a107d79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<h3 class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\tPrincipais marcas de bonecas sexuais\t\t\t\t<\/h3>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9aa171a elementor-widget elementor-widget-etheme_brands\" data-id=\"9aa171a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"etheme_brands.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <link rel=\"stylesheet\" href=\"https:\/\/renodoll.com\/wp-content\/themes\/xstore\/css\/modules\/woocommerce\/brands-carousel.min.css?ver=0.0.1\" type=\"text\/css\" media=\"all\" \/> \t\t\n            <div class=\"swiper-entry brands-carousel middle arrows-hover\">\n\n                <div class=\"swiper-container  brands-carousel-8658 stop-on-hover\" data-breakpoints=\"1\" data-xs-slides=\"1\" data-sm-slides=\"2\" data-md-slides=\"7\" data-lt-slides=\"7\" data-slides-per-view=\"7\" data-space=\"30\" data-autoplay=\"3000\" data-slides-per-group=\"1\" data-speed=\"300\" data-loop=\"true\">\n\n                    <div class=\"swiper-wrapper\">\n\n\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/pt\/brand\/6ye-doll\/\" title=\"Boneca 6YE\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-6ye.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-6ye.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-6ye-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-6ye-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-6ye-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <h3>\n                                <a href=\"https:\/\/renodoll.com\/pt\/brand\/aibei-doll\/\" title=\"View all products from Aibei Doll\">\n\t\t\t\t\t\t\t\t\tAibei Doll                                <\/a>\n                            <\/h3>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/pt\/brand\/angelkiss-doll\/\" title=\"Boneca AngelKiss\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-angelkiss.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-angelkiss.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-angelkiss-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-angelkiss-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-angelkiss-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/pt\/brand\/as-doll\/\" title=\"COMO Boneca\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-asdoll.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-asdoll.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-asdoll-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-asdoll-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-asdoll-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <h3>\n                                <a href=\"https:\/\/renodoll.com\/pt\/brand\/avant-doll\/\" title=\"View all products from Avant Doll\">\n\t\t\t\t\t\t\t\t\tAvant Doll                                <\/a>\n                            <\/h3>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <h3>\n                                <a href=\"https:\/\/renodoll.com\/pt\/brand\/chocolatelady-doll\/\" title=\"View all products from Chocolatelady Doll\">\n\t\t\t\t\t\t\t\t\tChocolatelady Doll                                <\/a>\n                            <\/h3>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <h3>\n                                <a href=\"https:\/\/renodoll.com\/pt\/brand\/cos-doll\/\" title=\"View all products from Cos Doll\">\n\t\t\t\t\t\t\t\t\tCos Doll                                <\/a>\n                            <\/h3>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/pt\/brand\/dh-doll\/\" title=\"Boneca D.H.\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-dh.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-dh.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-dh-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-dh-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-dh-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/pt\/brand\/elsababe-doll\/\" title=\"Boneca Elsababe\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-elsababe.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-elsababe.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-elsababe-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-elsababe-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-elsababe-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/pt\/brand\/fj-doll\/\" title=\"Boneca FJ\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-fj.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-fj.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-fj-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-fj-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-fj-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <h3>\n                                <a href=\"https:\/\/renodoll.com\/pt\/brand\/funwest-doll\/\" title=\"View all products from Funwest Doll\">\n\t\t\t\t\t\t\t\t\tFunwest Doll                                <\/a>\n                            <\/h3>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/pt\/brand\/gamelady-doll\/\" title=\"Boneca Game Lady\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-gamelady.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-gamelady.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-gamelady-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-gamelady-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-gamelady-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/pt\/brand\/hr-doll\/\" title=\"Boneca RH\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-hrdoll.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-hrdoll.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-hrdoll-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-hrdoll-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-hrdoll-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <h3>\n                                <a href=\"https:\/\/renodoll.com\/pt\/brand\/ido-doll\/\" title=\"View all products from Ido Doll\">\n\t\t\t\t\t\t\t\t\tIdo Doll                                <\/a>\n                            <\/h3>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/pt\/brand\/irontech-doll\/\" title=\"Boneca Irontech\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-irontechdoll.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-irontechdoll.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-irontechdoll-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-irontechdoll-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-irontechdoll-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/pt\/brand\/jarliet-doll\/\" title=\"Boneca Jarliet\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-jarliet.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-jarliet.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-jarliet-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-jarliet-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-jarliet-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/pt\/brand\/jinsan-doll\/\" title=\"Boneca Jinsan\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-jinsan.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-jinsan.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-jinsan-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-jinsan-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-jinsan-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <h3>\n                                <a href=\"https:\/\/renodoll.com\/pt\/brand\/kulove-doll\/\" title=\"View all products from Kulove Doll\">\n\t\t\t\t\t\t\t\t\tKulove Doll                                <\/a>\n                            <\/h3>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <h3>\n                                <a href=\"https:\/\/renodoll.com\/pt\/brand\/lily-doll\/\" title=\"View all products from Lily Doll\">\n\t\t\t\t\t\t\t\t\tLily Doll                                <\/a>\n                            <\/h3>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <h3>\n                                <a href=\"https:\/\/renodoll.com\/pt\/brand\/lusandy-doll\/\" title=\"View all products from Lusandy Doll\">\n\t\t\t\t\t\t\t\t\tLusandy Doll                                <\/a>\n                            <\/h3>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <h3>\n                                <a href=\"https:\/\/renodoll.com\/pt\/brand\/md-doll\/\" title=\"View all products from MD Doll\">\n\t\t\t\t\t\t\t\t\tMD Doll                                <\/a>\n                            <\/h3>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <h3>\n                                <a href=\"https:\/\/renodoll.com\/pt\/brand\/mmx-doll\/\" title=\"View all products from MMX Doll\">\n\t\t\t\t\t\t\t\t\tMMX Doll                                <\/a>\n                            <\/h3>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/pt\/brand\/or-doll\/\" title=\"OU Boneca\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-or.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-or.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-or-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-or-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-or-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <h3>\n                                <a href=\"https:\/\/renodoll.com\/pt\/brand\/ridmii-doll\/\" title=\"View all products from Ridmii Doll\">\n\t\t\t\t\t\t\t\t\tRidmii Doll                                <\/a>\n                            <\/h3>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <h3>\n                                <a href=\"https:\/\/renodoll.com\/pt\/brand\/rosretty-doll\/\" title=\"View all products from Rosretty Doll\">\n\t\t\t\t\t\t\t\t\tRosretty Doll                                <\/a>\n                            <\/h3>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/pt\/brand\/se-doll\/\" title=\"Boneca SE\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-se.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-se.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-se-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-se-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-se-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <h3>\n                                <a href=\"https:\/\/renodoll.com\/pt\/brand\/starpery-doll\/\" title=\"View all products from Starpery Doll\">\n\t\t\t\t\t\t\t\t\tStarpery Doll                                <\/a>\n                            <\/h3>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <h3>\n                                <a href=\"https:\/\/renodoll.com\/pt\/brand\/sweet-doll\/\" title=\"View all products from Sweet Doll\">\n\t\t\t\t\t\t\t\t\tSweet Doll                                <\/a>\n                            <\/h3>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <h3>\n                                <a href=\"https:\/\/renodoll.com\/pt\/brand\/top-fire-doll\/\" title=\"View all products from Top Fire Doll\">\n\t\t\t\t\t\t\t\t\tTop Fire Doll                                <\/a>\n                            <\/h3>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/pt\/brand\/wm-doll\/\" title=\"Boneca WM\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-wm.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-wm.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-wm-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-wm-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-wm-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <h3>\n                                <a href=\"https:\/\/renodoll.com\/pt\/brand\/xt-doll\/\" title=\"View all products from XT Doll\">\n\t\t\t\t\t\t\t\t\tXT Doll                                <\/a>\n                            <\/h3>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/pt\/brand\/yl-doll\/\" title=\"Boneca YL\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-yl.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-yl.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-yl-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-yl-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-yl-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/pt\/brand\/zelex-doll\/\" title=\"Boneca Zelex\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-zelex.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-zelex.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-zelex-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-zelex-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-zelex-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                    <\/div>\n\t\t\t\t\t\n                <\/div>\n\n\t\t\t\t\n                    <div class=\"swiper-button-prev swiper-custom-left swiper-nav et-swiper-elementor-nav type-arrow style-2\"><\/div>\n                    <div class=\"swiper-button-next swiper-custom-right swiper-nav et-swiper-elementor-nav type-arrow style-2\"><\/div>\n\n\t\t\t\t\t\t\t\t\t            <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Galeria de Bonecas Dimens\u00f5es da Boneca Material TPE Altura 165cm Peito 87cm Cintura 58cm Quadril 88cm Peso L\u00edquido 36KG Profundidade Oral 13cm Profundidade Vaginal 17cm Profundidade Anal 16cm Sobre a Boneca Apresentando bonecas sexuais reais - a companhia perfeita para os homens! Nossas bonecas anatomicamente corretas em tamanho real s\u00e3o projetadas para proporcionar a melhor experi\u00eancia de prazer. Feitas com materiais de silicone TPE da mais alta qualidade, essas bonecas s\u00e3o projetadas para parecer e se sentir como uma mulher de verdade. Com caracter\u00edsticas e formas corporais realistas, essas bonecas proporcionam uma experi\u00eancia sexual realista. Para maior conveni\u00eancia, essas bonecas podem at\u00e9 ser infladas para um conforto maior<\/p>","protected":false},"featured_media":10268,"comment_status":"open","ping_status":"closed","template":"","meta":[],"etheme_brands":[{"term_id":57,"name":"6YE Doll","slug":"6ye-doll","term_group":0,"term_taxonomy_id":57,"taxonomy":"brand","description":"","parent":0,"count":133,"filter":"raw"}],"product_brand":[],"product_cat":[65,26,67,60,53],"product_tag":[],"class_list":{"0":"post-10267","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"brand-6ye-doll","7":"product_cat-160cm-169cm","8":"product_cat-big-boobs-sex-doll","9":"product_cat-fat-sex-doll","10":"product_cat-real-sex-dolls","11":"product_cat-tpe-sex-doll","12":"tm-has-options","14":"first","15":"instock","16":"sale","17":"shipping-taxable","18":"purchasable","19":"product-type-simple"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/renodoll.com\/pt\/wp-json\/wp\/v2\/product\/10267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/renodoll.com\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/renodoll.com\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/renodoll.com\/pt\/wp-json\/wp\/v2\/comments?post=10267"}],"version-history":[{"count":4,"href":"https:\/\/renodoll.com\/pt\/wp-json\/wp\/v2\/product\/10267\/revisions"}],"predecessor-version":[{"id":55925,"href":"https:\/\/renodoll.com\/pt\/wp-json\/wp\/v2\/product\/10267\/revisions\/55925"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/renodoll.com\/pt\/wp-json\/wp\/v2\/media\/10268"}],"wp:attachment":[{"href":"https:\/\/renodoll.com\/pt\/wp-json\/wp\/v2\/media?parent=10267"}],"wp:term":[{"taxonomy":"brand","embeddable":true,"href":"https:\/\/renodoll.com\/pt\/wp-json\/wp\/v2\/etheme_brands?post=10267"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/renodoll.com\/pt\/wp-json\/wp\/v2\/product_brand?post=10267"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/renodoll.com\/pt\/wp-json\/wp\/v2\/product_cat?post=10267"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/renodoll.com\/pt\/wp-json\/wp\/v2\/product_tag?post=10267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}