{"id":12496,"date":"2023-03-21T03:23:19","date_gmt":"2023-03-20T19:23:19","guid":{"rendered":"https:\/\/renodoll.com\/?post_type=product&#038;p=12496"},"modified":"2023-09-08T10:36:10","modified_gmt":"2023-09-08T02:36:10","slug":"full-sized-solid-synthetic-female-doll","status":"publish","type":"product","link":"https:\/\/renodoll.com\/nb\/products\/full-sized-solid-synthetic-female-doll\/","title":{"rendered":"Full st\u00f8rrelse solid syntetisk kvinnedukke Carina 168cm"},"content":{"rendered":"<div class=\"product_desc_section\">\n<h3 style=\"text-align: left;\"><strong>Dukkegalleri<\/strong><\/h3>\n<div class=\"doll_gallery_section\">\t                <ul class=\"easy-image-gallery thumbnails-23 linked\">\r\n                    <li><a data-fancybox=\"gallery533\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a1.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a1-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a1-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a1-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery533\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a2.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a2-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a2-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a2-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery533\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a3.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a3-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a3-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a3-300x300.jpg 300w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a3-768x768.jpg 768w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a3-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a3-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a3-600x600.jpg 600w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a3-10x10.jpg 10w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a3.jpg 900w\" \/><\/a><\/li><li><a data-fancybox=\"gallery533\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a4.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a4-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a4-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a4-300x300.jpg 300w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a4-768x768.jpg 768w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a4-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a4-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a4-600x600.jpg 600w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a4-10x10.jpg 10w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a4.jpg 900w\" \/><\/a><\/li><li><a data-fancybox=\"gallery533\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a8.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a8-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a8-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a8-300x300.jpg 300w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a8-768x768.jpg 768w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a8-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a8-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a8-600x600.jpg 600w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a8-10x10.jpg 10w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a8.jpg 900w\" \/><\/a><\/li><li><a data-fancybox=\"gallery533\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a9.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a9-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a9-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a9-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery533\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a10.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a10-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a10-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a10-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery533\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a11.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a11-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a11-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a11-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery533\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a12.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a12-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a12-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a12-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery533\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a13.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a13-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a13-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a13-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery533\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a14.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a14-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a14-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a14-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery533\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a15.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a15-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a15-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a15-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery533\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a16.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a16-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a16-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a16-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery533\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a17.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a17-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a17-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a17-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery533\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a18.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a18-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a18-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a18-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery533\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a19.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a19-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a19-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a19-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery533\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a20.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a20-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a20-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a20-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery533\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a21.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a21-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a21-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a21-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery533\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a23.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a23-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a23-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a23-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery533\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a25.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a25-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a25-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a25-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery533\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a26.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a26-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a26-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a26-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery533\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a27.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a27-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a27-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a27-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery533\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a28.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a28-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a28-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/03\/best-tpe-sex-doll-z8a28-100x100.jpg 100w\" \/><\/a><\/li><\/ul><\/div>\n<div class=\"clear_both\"><\/div>\n<div class=\"product_desc_col1\">\n<h3 style=\"text-align: left;\"><strong>Dukkedimensjoner<\/strong><\/h3>\n<table width=\"269\">\n<tbody>\n<tr>\n<td width=\"130\">Materiale<\/td>\n<td width=\"139\">TPE<\/td>\n<\/tr>\n<tr>\n<td>H\u00f8yde<\/td>\n<td>168 cm<\/td>\n<\/tr>\n<tr>\n<td>Bryst<\/td>\n<td>79 cm<\/td>\n<\/tr>\n<tr>\n<td>Midje<\/td>\n<td>59 cm<\/td>\n<\/tr>\n<tr>\n<td>Hofte<\/td>\n<td>87 cm<\/td>\n<\/tr>\n<tr>\n<td>Netto vekt<\/td>\n<td>39 kg<\/td>\n<\/tr>\n<tr>\n<td>Muntlig dybde<\/td>\n<td>12 cm<\/td>\n<\/tr>\n<tr>\n<td>Vaginal dybde<\/td>\n<td>22 cm<\/td>\n<\/tr>\n<tr>\n<td>Anal dybde<\/td>\n<td>18 cm<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<div class=\"product_desc_col1\">\n<h3><strong>Om dukken<\/strong><\/h3>\n<p>Det er fordeler med halvsolide sexdukker, og en av fordelene med de beste sexdukkene noensinne er deres allsidighet. De kan tilpasses med en rekke tilbeh\u00f8r og kl\u00e6r, slik at brukerne kan lage sine egne unike fantasiscenarier. I tillegg betyr det at de er mer b\u00e6rbare enn dukker i full st\u00f8rrelse at de diskret kan oppbevares n\u00e5r de ikke er i bruk.<\/p>\n<p>Til syvende og sist, hvorvidt en semi-oppbl\u00e5sbar dukke er det riktige valget for en person, er en personlig avgj\u00f8relse som avhenger av en rekke faktorer, inkludert personlige preferanser, budsjett og livsstil. Som med alle typer sexleket\u00f8y, er det viktig \u00e5 gj\u00f8re research og finne ut hva du virkelig liker. Syntetiske kvinnelige dukker er realistiske kopier av mannlige menneskekropper som kan brukes som sexleket\u00f8y eller f\u00f8lgesvenner. Disse solide sexdukkene er laget av syntetiske materialer som silikon eller TPE, og er designet for \u00e5 se ut og f\u00f8les som et ekte menneske.<\/p>\n<p>En av de viktigste fordelene med en syntetisk kvinnelig dukke er graden av tilpasning de tilbyr. Kunder kan velge mellom et bredt utvalg av kroppstyper, hudfarger og ansiktstrekk for \u00e5 lage en dukke som oppfyller deres eksakte preferanser, og dette er den beste sexdukken noensinne. Noen kvinnelige dukker kommer til og med med utskiftbare deler, slik at brukerne kan bytte ut forskjellige funksjoner som h\u00e5r og kj\u00f8nnsorganer for \u00e5 skape en mer personlig opplevelse.<\/p>\n<\/div>\n<div class=\"clear_both\"><\/div>\n<div class=\"product_desc_row\">\n<h3 style=\"text-align: left;\"><strong>Mer informasjon<\/strong><\/h3>\n\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"5107\" class=\"elementor elementor-5107\" data-elementor-post-type=\"staticblocks\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f4da12a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f4da12a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d6a2412\" data-id=\"d6a2412\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e7bba8 elementor-widget-divider--view-line_text elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"7e7bba8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<h3 class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\tSkjelettshow fra WM Dolls\t\t\t\t<\/h3>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-abc0118 elementor-widget elementor-widget-image\" data-id=\"abc0118\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"693\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/elementor\/thumbs\/xstore-placeholder-q1lsnz7fehkm1srdmxtn5lk7se7rj04saxv7z16xig.png\" class=\"attachment-full size-full wp-image-63174 lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/06\/pages-skeleton-1.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/06\/pages-skeleton-1.jpg 1500w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/06\/pages-skeleton-1-300x139.jpg 300w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/06\/pages-skeleton-1-1024x473.jpg 1024w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/06\/pages-skeleton-1-768x355.jpg 768w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/06\/pages-skeleton-1-18x8.jpg 18w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/06\/pages-skeleton-1-100x46.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/06\/pages-skeleton-1-600x277.jpg 600w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/06\/pages-skeleton-1-10x5.jpg 10w\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5cff75b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5cff75b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4952662\" data-id=\"4952662\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac8a6d7 elementor-widget-divider--view-line_text elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"ac8a6d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<h3 class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\tKunnskapsbase for sexdukke\t\t\t\t<\/h3>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-80290db elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"80290db\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-942d32c\" data-id=\"942d32c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f528340 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"f528340\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/nb\/automatic-sex-doll\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> Automatisk sexdukke<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/nb\/auto-blowjob-sex-doll\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Auto Blowjob Sex Doll<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/nb\/electric-hip-sex-doll\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Elektrisk hip sexdukke<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/nb\/articulated-finger\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Artikulert finger<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/nb\/evo-yoga-skeleton\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">EVO Yoga skjelett<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/nb\/what-is-a-sex-doll\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Hva er en sexdukke?<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/nb\/sex-doll-care\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Sexdukkepleie<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b322228\" data-id=\"b322228\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c591da9 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"c591da9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/nb\/sex-doll-dress-up\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Sexdukke kle seg<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/nb\/sex-doll-skeleton\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Sexdukkeskjelett<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/nb\/sex-doll-breast-options\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Brystalternativer for sexdukker<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/nb\/heating-system\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> Varmesystem<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/nb\/sex-doll-moaning\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Sexdukke St\u00f8nne<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/nb\/sex-doll-tongue\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Sexdukke Tunge<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-f9e8f13\" data-id=\"f9e8f13\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51a1c15 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"51a1c15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/nb\/blood-vessel\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Blod\u00e5re<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/nb\/sex-doll-maintenance\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Vedlikehold av sexdukke<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/nb\/movement-range\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Bevegelsesomr\u00e5de<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/nb\/standing-without-bolts\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">St\u00e5ende uten bolter<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/nb\/freckles\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Fregner maleri<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/nb\/sex-doll-storage\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Oppbevaring av sexdukker<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-854f952 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"854f952\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ec5780d\" data-id=\"ec5780d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a107d79 elementor-widget-divider--view-line_text elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"a107d79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<h3 class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\tTopp sexdukkemerker\t\t\t\t<\/h3>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9aa171a elementor-widget elementor-widget-etheme_brands\" data-id=\"9aa171a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"etheme_brands.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <link rel=\"stylesheet\" href=\"https:\/\/renodoll.com\/wp-content\/themes\/xstore\/css\/modules\/woocommerce\/brands-carousel.min.css?ver=0.0.1\" type=\"text\/css\" media=\"all\" \/> \t\t\n            <div class=\"swiper-entry brands-carousel middle arrows-hover\">\n\n                <div class=\"swiper-container  brands-carousel-6962 stop-on-hover\" data-breakpoints=\"1\" data-xs-slides=\"1\" data-sm-slides=\"2\" data-md-slides=\"7\" data-lt-slides=\"7\" data-slides-per-view=\"7\" data-space=\"30\" data-autoplay=\"3000\" data-slides-per-group=\"1\" data-speed=\"300\" data-loop=\"true\">\n\n                    <div class=\"swiper-wrapper\">\n\n\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/nb\/brand\/6ye-doll\/\" title=\"6YE dukke\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-6ye.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-6ye.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-6ye-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-6ye-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-6ye-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/nb\/brand\/angelkiss-doll\/\" title=\"AngelKiss Doll\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-angelkiss.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-angelkiss.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-angelkiss-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-angelkiss-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-angelkiss-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/nb\/brand\/as-doll\/\" title=\"AS dukke\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-asdoll.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-asdoll.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-asdoll-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-asdoll-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-asdoll-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/nb\/brand\/dh-doll\/\" title=\"DH dukke\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-dh.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-dh.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-dh-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-dh-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-dh-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/nb\/brand\/elsababe-doll\/\" title=\"Elsababe dukke\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-elsababe.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-elsababe.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-elsababe-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-elsababe-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-elsababe-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/nb\/brand\/fj-doll\/\" title=\"FJ dukke\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-fj.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-fj.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-fj-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-fj-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-fj-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/nb\/brand\/gamelady-doll\/\" title=\"GameLady Doll\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-gamelady.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-gamelady.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-gamelady-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-gamelady-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-gamelady-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/nb\/brand\/hr-doll\/\" title=\"HR-dukke\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-hrdoll.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-hrdoll.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-hrdoll-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-hrdoll-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-hrdoll-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/nb\/brand\/irontech-doll\/\" title=\"Irontech dukke\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-irontechdoll.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-irontechdoll.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-irontechdoll-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-irontechdoll-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-irontechdoll-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/nb\/brand\/jarliet-doll\/\" title=\"Jarliet dukke\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-jarliet.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-jarliet.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-jarliet-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-jarliet-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-jarliet-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/nb\/brand\/jinsan-doll\/\" title=\"Jinsan dukke\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-jinsan.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-jinsan.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-jinsan-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-jinsan-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-jinsan-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/nb\/brand\/or-doll\/\" title=\"ELLER dukke\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-or.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-or.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-or-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-or-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-or-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/nb\/brand\/se-doll\/\" title=\"SE dukke\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-se.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-se.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-se-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-se-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-se-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/nb\/brand\/wm-doll\/\" title=\"WM dukke\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-wm.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-wm.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-wm-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-wm-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-wm-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/nb\/brand\/yl-doll\/\" title=\"YL dukke\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-yl.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-yl.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-yl-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-yl-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-yl-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/nb\/brand\/zelex-doll\/\" title=\"Zelex dukke\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-zelex.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-zelex.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-zelex-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-zelex-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-zelex-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                    <\/div>\n\t\t\t\t\t\n                <\/div>\n\n\t\t\t\t\n                    <div class=\"swiper-button-prev swiper-custom-left swiper-nav et-swiper-elementor-nav type-arrow style-2\"><\/div>\n                    <div class=\"swiper-button-next swiper-custom-right swiper-nav et-swiper-elementor-nav type-arrow style-2\"><\/div>\n\n\t\t\t\t\t\t\t\t\t            <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Dukkegalleri Dukkedimensjoner Materiale TPE H\u00f8yde 168cm Bryst 79cm Midje 59cm Hofte 87cm Nettovekt 39KG Oraldybde 12cm Vaginaldybde 22cm Analdybde 18cm Om dukken Det er fordeler med halvsolide sexdukker og en av disse fordelene med den beste sexdukken noensinne allsidighet. De kan tilpasses med en rekke tilbeh\u00f8r og kl\u00e6r, slik at brukerne kan lage sine egne unike fantasiscenarier. I tillegg betyr det at de er mer b\u00e6rbare enn dukker i full st\u00f8rrelse at de diskret kan oppbevares n\u00e5r de ikke er i bruk. Til syvende og sist, enten en semi-oppbl\u00e5sbar eller ikke<\/p>","protected":false},"featured_media":12513,"comment_status":"open","ping_status":"closed","template":"","meta":[],"etheme_brands":[{"term_id":59,"name":"HR Doll","slug":"hr-doll","term_group":0,"term_taxonomy_id":59,"taxonomy":"brand","description":"","parent":0,"count":104,"filter":"raw"}],"product_brand":[],"product_cat":[65,67,62,52,53],"product_tag":[],"class_list":{"0":"post-12496","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"brand-hr-doll","7":"product_cat-160cm-169cm","8":"product_cat-fat-sex-doll","9":"product_cat-life-size-sex-dolls","10":"product_cat-small-breast-sex-doll","11":"product_cat-tpe-sex-doll","12":"tm-has-options","14":"first","15":"instock","16":"sale","17":"shipping-taxable","18":"purchasable","19":"product-type-simple"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/renodoll.com\/nb\/wp-json\/wp\/v2\/product\/12496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/renodoll.com\/nb\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/renodoll.com\/nb\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/renodoll.com\/nb\/wp-json\/wp\/v2\/comments?post=12496"}],"version-history":[{"count":3,"href":"https:\/\/renodoll.com\/nb\/wp-json\/wp\/v2\/product\/12496\/revisions"}],"predecessor-version":[{"id":56172,"href":"https:\/\/renodoll.com\/nb\/wp-json\/wp\/v2\/product\/12496\/revisions\/56172"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/renodoll.com\/nb\/wp-json\/wp\/v2\/media\/12513"}],"wp:attachment":[{"href":"https:\/\/renodoll.com\/nb\/wp-json\/wp\/v2\/media?parent=12496"}],"wp:term":[{"taxonomy":"brand","embeddable":true,"href":"https:\/\/renodoll.com\/nb\/wp-json\/wp\/v2\/etheme_brands?post=12496"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/renodoll.com\/nb\/wp-json\/wp\/v2\/product_brand?post=12496"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/renodoll.com\/nb\/wp-json\/wp\/v2\/product_cat?post=12496"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/renodoll.com\/nb\/wp-json\/wp\/v2\/product_tag?post=12496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}