{"id":96,"count":76,"description":"","link":"https:\/\/renodoll.com\/nb\/brand\/fj-doll\/","name":"FJ Doll","slug":"fj-doll","taxonomy":"brand","parent":0,"meta":{"thumbnail_id":["63113"],"_trp_automatically_translated_slug_de_DE":["fj-puppe"],"_trp_automatically_translated_slug_fr_FR":["fj-poupee"],"_trp_automatically_translated_slug_nl_NL":["fj-pop"],"_trp_automatically_translated_slug_es_ES":["muneca-fj"],"_trp_automatically_translated_slug_it_IT":["fj-bambola"],"_aioseo_title":[null],"_aioseo_description":[null],"_aioseo_keywords":[""],"_aioseo_og_title":[null],"_aioseo_og_description":[null],"_aioseo_og_article_section":[""],"_aioseo_og_article_tags":[""],"_aioseo_twitter_title":[null],"_aioseo_twitter_description":[null],"_trp_automatically_translated_slug_fi":["fj-nukke"],"_trp_automatically_translated_slug_sv_SE":["fj-docka"],"_trp_automatically_translated_slug_pl_PL":["lalka-fj"],"_trp_automatically_translated_slug_et":["fj-nukk"],"_trp_automatically_translated_slug_sl_SI":["fj-lutka"],"_trp_automatically_translated_slug_lt_LT":["fj-lele"],"_trp_automatically_translated_slug_hr":["fj-lutka"],"_trp_automatically_translated_slug_nb_NO":["fj-dukke"],"_trp_automatically_translated_slug_sk_SK":["fj-babika"],"_trp_automatically_translated_slug_hu_HU":["fj-baba"],"_trp_automatically_translated_slug_el":["fj-%ce%ba%ce%bf%cf%8d%ce%ba%ce%bb%ce%b1"],"_trp_automatically_translated_slug_bg_BG":["fj-%d0%ba%d1%83%d0%ba%d0%bb%d0%b0"],"_trp_automatically_translated_slug_cs_CZ":["fj-panenka"],"_trp_automatically_translated_slug_ro_RO":["fj-doll"],"_trp_automatically_translated_slug_lv":["fj-lelle"],"_trp_automatically_translated_slug_pt_PT":["boneca-fj"],"_trp_automatically_translated_slug_da_DK":["fj-dukke"]},"image":{"id":["63113"],"src":"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-fj.jpg","alt":[],"title":"logo-fj","caption":"#image_title","description":"#image_title"},"_links":{"self":[{"href":"https:\/\/renodoll.com\/nb\/wp-json\/wp\/v2\/etheme_brands\/96","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/renodoll.com\/nb\/wp-json\/wp\/v2\/etheme_brands"}],"about":[{"href":"https:\/\/renodoll.com\/nb\/wp-json\/wp\/v2\/taxonomies\/brand"}],"wp:post_type":[{"href":"https:\/\/renodoll.com\/nb\/wp-json\/wp\/v2\/product?etheme_brands=96"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}