{"id":58514,"date":"2023-09-27T01:04:00","date_gmt":"2023-09-26T17:04:00","guid":{"rendered":"https:\/\/renodoll.com\/?post_type=product&#038;p=58514"},"modified":"2023-10-07T14:36:39","modified_gmt":"2023-10-07T06:36:39","slug":"micro-doll-sex-toy-hard-fuck","status":"publish","type":"product","link":"https:\/\/renodoll.com\/hr\/products\/micro-doll-sex-toy-hard-fuck\/","title":{"rendered":"Mikro lutka seks igra\u010dka Hard Fuck Claus 165 cm"},"content":{"rendered":"<div class=\"product_desc_section\">\n<h3 style=\"text-align: left;\"><strong>Galerija lutaka<\/strong><\/h3>\n<div class=\"doll_gallery_section\">\t                <ul class=\"easy-image-gallery thumbnails-19 linked\">\r\n                    <li><a data-fancybox=\"gallery802\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun1.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun1-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun1-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun1-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery802\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun2.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun2-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun2-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun2-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery802\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun3.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun3-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun3-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun3-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery802\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun4.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun4-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun4-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun4-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery802\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun5.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun5-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun5-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun5-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery802\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun6.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun6-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun6-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun6-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery802\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun7.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun7-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun7-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun7-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery802\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun8.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun8-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun8-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun8-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery802\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun9.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun9-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun9-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun9-298x300.jpg 298w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun9-768x774.jpg 768w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun9-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun9-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun9-300x302.jpg 300w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun9-600x605.jpg 600w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun9-10x10.jpg 10w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun9.jpg 893w\" \/><\/a><\/li><li><a data-fancybox=\"gallery802\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun10.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun10-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun10-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun10-11x12.jpg 11w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun10-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun10-10x10.jpg 10w\" \/><\/a><\/li><li><a data-fancybox=\"gallery802\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun11.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun11-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun11-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun11-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery802\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun12.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun12-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun12-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun12-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery802\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun13.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun13-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun13-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun13-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery802\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun14.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun14-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun14-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun14-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery802\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun15.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun15-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun15-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun15-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery802\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun16.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun16-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun16-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun16-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery802\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun17.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun17-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun17-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun17-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery802\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun18.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun18-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun18-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun18-100x100.jpg 100w\" \/><\/a><\/li><li><a data-fancybox=\"gallery802\" href=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun19.jpg\" class=\"eig-popup\" title=\"#image_title\" data-caption=\"#image_title\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-thumbnail size-thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun19-150x150.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun19-150x150.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/09\/lifelike-male-doll-g9iun19-100x100.jpg 100w\" \/><\/a><\/li><\/ul><\/div>\n<div class=\"clear_both\"><\/div>\n<div class=\"product_desc_col1\">\n<h3 style=\"text-align: left;\"><strong>Dimenzije lutke<\/strong><\/h3>\n<table width=\"358\">\n<tbody>\n<tr>\n<td width=\"145\">Materijal<\/td>\n<td width=\"213\">TPE<\/td>\n<\/tr>\n<tr>\n<td>Visina<\/td>\n<td>165 cm<\/td>\n<\/tr>\n<tr>\n<td>Neto te\u017eina<\/td>\n<td>43 kg<\/td>\n<\/tr>\n<tr>\n<td>Poprsje<\/td>\n<td>85 cm<\/td>\n<\/tr>\n<tr>\n<td>Struk<\/td>\n<td>70 cm<\/td>\n<\/tr>\n<tr>\n<td>Hip<\/td>\n<td>90 cm<\/td>\n<\/tr>\n<tr>\n<td>Ruka<\/td>\n<td>72 cm<\/td>\n<\/tr>\n<tr>\n<td>Rame<\/td>\n<td>42 cm<\/td>\n<\/tr>\n<tr>\n<td>Du\u017eina noge<\/td>\n<td>95 cm<\/td>\n<\/tr>\n<tr>\n<td>Du\u017eina stopala<\/td>\n<td>23 cm<\/td>\n<\/tr>\n<tr>\n<td>Oralna dubina<\/td>\n<td>12 cm<\/td>\n<\/tr>\n<tr>\n<td>Analna dubina<\/td>\n<td>20 cm<\/td>\n<\/tr>\n<tr>\n<td>Meki penis<\/td>\n<td>8 cm (duljina) * 4 cm (okrug)<\/td>\n<\/tr>\n<tr>\n<td>Tvrdi penis<\/td>\n<td>16 cm (duljina) * 4,5 cm (okrug)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<div class=\"product_desc_col1\">\n<h3><strong>O lutki<\/strong><\/h3>\n\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"16236\" class=\"elementor elementor-16236\" data-elementor-post-type=\"staticblocks\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-75eb1f80 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"75eb1f80\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-70392c7b\" data-id=\"70392c7b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b8ce90 elementor-widget elementor-widget-text-editor\" data-id=\"7b8ce90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Tijekom godina isporu\u010dili smo mnogo kvalitetnih i u\u010dinkovitih seks lutaka. Na\u0161e usluge pru\u017eaju zadovoljstvo za koje bi \u010dovjek pomislio da je izvan zamislivog. Na\u0161i proizvodi su 100% dobri, a na\u0161 sustav pla\u0107anja je fleksibilan, sa sustavom jamstva povrata novca za na\u0161e seks lutke.<\/li><li>Na\u0161e realisti\u010dne ljubavne lutke dolaze u svim nijansama po pristupa\u010dnim cijenama, izvrsnom otpremom proizvoda, bez stresa i fleksibilno\u0161\u0107u.<\/li><li>RenoDoll proizvode mo\u017eete provjeriti na svim forumima o lutkama. Hvalimo se izvrsnim i ohrabruju\u0107im recenzijama proizvoda, najvi\u0161im ocjenama od pet zvjezdica i recenzijama, te niti jednom negativnom recenzijom, \u0161to vas dodatno uvjerava u maksimalnu kvalitetu koja dolazi s na\u0161im proizvodima.<\/li><li>Mi smo izuzetno u\u010dinkovit tim. Na\u0161i re\u017eijski tro\u0161kovi su niski, \u0161to vam poma\u017ee da potro\u0161ite manje na kvalitetne seks lutke kada kupujete od nas.<\/li><li>Tako\u0111er se mo\u017eemo pohvaliti izvanrednom uslugom izme\u0111u kupaca i proizvo\u0111a\u010da. Na\u0161 uslu\u017eni tim uvijek je spreman saslu\u0161ati i pru\u017eiti potrebno te raditi na povratnim informacijama na\u0161ih kupaca. Na\u0161i su klijenti na\u0161 glavni prioritet i naporno radimo kako bismo bili sigurni da je svaki kupac zadovoljan i da mu je pru\u017eeno najbolje \u0161to zaslu\u017euje.<\/li><\/ul><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\n<\/div>\n<div class=\"clear_both\"><\/div>\n<div class=\"product_desc_row\">\n<h3 style=\"text-align: left;\"><strong>Vi\u0161e informacija<\/strong><\/h3>\n\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"5107\" class=\"elementor elementor-5107\" data-elementor-post-type=\"staticblocks\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f4da12a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f4da12a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d6a2412\" data-id=\"d6a2412\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e7bba8 elementor-widget-divider--view-line_text elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"7e7bba8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<h3 class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\tSkeleton Show iz WM Dolls\t\t\t\t<\/h3>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-abc0118 elementor-widget elementor-widget-image\" data-id=\"abc0118\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"693\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/elementor\/thumbs\/xstore-placeholder-q1lsnz7fehkm1srdmxtn5lk7se7rj04saxv7z16xig.png\" class=\"attachment-full size-full wp-image-63174 lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/06\/pages-skeleton-1.jpg\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/06\/pages-skeleton-1.jpg 1500w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/06\/pages-skeleton-1-300x139.jpg 300w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/06\/pages-skeleton-1-1024x473.jpg 1024w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/06\/pages-skeleton-1-768x355.jpg 768w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/06\/pages-skeleton-1-18x8.jpg 18w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/06\/pages-skeleton-1-100x46.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/06\/pages-skeleton-1-600x277.jpg 600w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/06\/pages-skeleton-1-10x5.jpg 10w\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5cff75b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5cff75b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4952662\" data-id=\"4952662\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac8a6d7 elementor-widget-divider--view-line_text elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"ac8a6d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<h3 class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\tBaza znanja Sex Doll\t\t\t\t<\/h3>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-80290db elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"80290db\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-942d32c\" data-id=\"942d32c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f528340 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"f528340\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/hr\/automatic-sex-doll\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> Automatska seks lutka<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/hr\/auto-blowjob-sex-doll\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Lutka za seks s automatskim pu\u0161enjem<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/hr\/electric-hip-sex-doll\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Elektri\u010dna seks lutka za bokove<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/hr\/articulated-finger\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Zglobni prst<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/hr\/evo-yoga-skeleton\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">EVO Yoga Skeleton<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/hr\/what-is-a-sex-doll\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0160to je seks lutka?<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/hr\/sex-doll-care\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Njega seksualne lutke<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b322228\" data-id=\"b322228\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c591da9 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"c591da9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/hr\/sex-doll-dress-up\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Obla\u010denje seks lutke<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/hr\/sex-doll-skeleton\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Kostur seksualne lutke<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/hr\/sex-doll-breast-options\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Opcije grudi Sex Doll<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/hr\/heating-system\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> Sistem grijanja<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/hr\/sex-doll-moaning\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Sex Doll stenje<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/hr\/sex-doll-tongue\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Jezik seksualne lutke<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-f9e8f13\" data-id=\"f9e8f13\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51a1c15 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"51a1c15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/hr\/blood-vessel\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Krvna \u017eila<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/hr\/sex-doll-maintenance\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Odr\u017eavanje seks lutaka<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/hr\/movement-range\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Raspon kretanja<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/hr\/standing-without-bolts\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Stoji bez vijaka<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/hr\/freckles\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Slikanje pjega<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/renodoll.com\/hr\/sex-doll-storage\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Skladi\u0161tenje seks lutaka<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-854f952 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"854f952\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ec5780d\" data-id=\"ec5780d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a107d79 elementor-widget-divider--view-line_text elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"a107d79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<h3 class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\tNajpopularnije marke seks lutaka\t\t\t\t<\/h3>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9aa171a elementor-widget elementor-widget-etheme_brands\" data-id=\"9aa171a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"etheme_brands.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <link rel=\"stylesheet\" href=\"https:\/\/renodoll.com\/wp-content\/themes\/xstore\/css\/modules\/woocommerce\/brands-carousel.min.css?ver=0.0.1\" type=\"text\/css\" media=\"all\" \/> \t\t\n            <div class=\"swiper-entry brands-carousel middle arrows-hover\">\n\n                <div class=\"swiper-container  brands-carousel-1654 stop-on-hover\" data-breakpoints=\"1\" data-xs-slides=\"1\" data-sm-slides=\"2\" data-md-slides=\"7\" data-lt-slides=\"7\" data-slides-per-view=\"7\" data-space=\"30\" data-autoplay=\"3000\" data-slides-per-group=\"1\" data-speed=\"300\" data-loop=\"true\">\n\n                    <div class=\"swiper-wrapper\">\n\n\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/hr\/brand\/6ye-doll\/\" title=\"6YE lutka\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-6ye.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-6ye.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-6ye-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-6ye-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-6ye-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <h3>\n                                <a href=\"https:\/\/renodoll.com\/hr\/brand\/aibei-doll\/\" title=\"View all products from Aibei Doll\">\n\t\t\t\t\t\t\t\t\tAibei Doll                                <\/a>\n                            <\/h3>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/hr\/brand\/angelkiss-doll\/\" title=\"Lutka AngelKiss\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-angelkiss.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-angelkiss.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-angelkiss-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-angelkiss-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-angelkiss-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/hr\/brand\/as-doll\/\" title=\"KAO Lutka\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-asdoll.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-asdoll.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-asdoll-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-asdoll-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-asdoll-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <h3>\n                                <a href=\"https:\/\/renodoll.com\/hr\/brand\/avant-doll\/\" title=\"View all products from Avant Doll\">\n\t\t\t\t\t\t\t\t\tAvant Doll                                <\/a>\n                            <\/h3>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <h3>\n                                <a href=\"https:\/\/renodoll.com\/hr\/brand\/chocolatelady-doll\/\" title=\"View all products from Chocolatelady Doll\">\n\t\t\t\t\t\t\t\t\tChocolatelady Doll                                <\/a>\n                            <\/h3>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <h3>\n                                <a href=\"https:\/\/renodoll.com\/hr\/brand\/cos-doll\/\" title=\"View all products from Cos Doll\">\n\t\t\t\t\t\t\t\t\tCos Doll                                <\/a>\n                            <\/h3>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/hr\/brand\/dh-doll\/\" title=\"DH lutka\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-dh.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-dh.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-dh-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-dh-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-dh-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/hr\/brand\/elsababe-doll\/\" title=\"Lutka Elsababe\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-elsababe.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-elsababe.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-elsababe-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-elsababe-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-elsababe-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/hr\/brand\/fj-doll\/\" title=\"FJ lutka\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-fj.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-fj.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-fj-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-fj-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-fj-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <h3>\n                                <a href=\"https:\/\/renodoll.com\/hr\/brand\/funwest-doll\/\" title=\"View all products from Funwest Doll\">\n\t\t\t\t\t\t\t\t\tFunwest Doll                                <\/a>\n                            <\/h3>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/hr\/brand\/gamelady-doll\/\" title=\"Lutka GameLady\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-gamelady.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-gamelady.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-gamelady-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-gamelady-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-gamelady-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/hr\/brand\/hr-doll\/\" title=\"HR lutka\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-hrdoll.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-hrdoll.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-hrdoll-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-hrdoll-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-hrdoll-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <h3>\n                                <a href=\"https:\/\/renodoll.com\/hr\/brand\/ido-doll\/\" title=\"View all products from Ido Doll\">\n\t\t\t\t\t\t\t\t\tIdo Doll                                <\/a>\n                            <\/h3>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/hr\/brand\/irontech-doll\/\" title=\"Irontech lutka\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-irontechdoll.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-irontechdoll.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-irontechdoll-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-irontechdoll-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-irontechdoll-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/hr\/brand\/jarliet-doll\/\" title=\"Lutka Jarliet\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-jarliet.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-jarliet.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-jarliet-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-jarliet-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-jarliet-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/hr\/brand\/jinsan-doll\/\" title=\"Jinsan lutka\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-jinsan.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-jinsan.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-jinsan-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-jinsan-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-jinsan-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <h3>\n                                <a href=\"https:\/\/renodoll.com\/hr\/brand\/kulove-doll\/\" title=\"View all products from Kulove Doll\">\n\t\t\t\t\t\t\t\t\tKulove Doll                                <\/a>\n                            <\/h3>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <h3>\n                                <a href=\"https:\/\/renodoll.com\/hr\/brand\/lily-doll\/\" title=\"View all products from Lily Doll\">\n\t\t\t\t\t\t\t\t\tLily Doll                                <\/a>\n                            <\/h3>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <h3>\n                                <a href=\"https:\/\/renodoll.com\/hr\/brand\/lusandy-doll\/\" title=\"View all products from Lusandy Doll\">\n\t\t\t\t\t\t\t\t\tLusandy Doll                                <\/a>\n                            <\/h3>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <h3>\n                                <a href=\"https:\/\/renodoll.com\/hr\/brand\/md-doll\/\" title=\"View all products from MD Doll\">\n\t\t\t\t\t\t\t\t\tMD Doll                                <\/a>\n                            <\/h3>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <h3>\n                                <a href=\"https:\/\/renodoll.com\/hr\/brand\/mmx-doll\/\" title=\"View all products from MMX Doll\">\n\t\t\t\t\t\t\t\t\tMMX Doll                                <\/a>\n                            <\/h3>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/hr\/brand\/or-doll\/\" title=\"ILI Lutka\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-or.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-or.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-or-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-or-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-or-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <h3>\n                                <a href=\"https:\/\/renodoll.com\/hr\/brand\/ridmii-doll\/\" title=\"View all products from Ridmii Doll\">\n\t\t\t\t\t\t\t\t\tRidmii Doll                                <\/a>\n                            <\/h3>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <h3>\n                                <a href=\"https:\/\/renodoll.com\/hr\/brand\/rosretty-doll\/\" title=\"View all products from Rosretty Doll\">\n\t\t\t\t\t\t\t\t\tRosretty Doll                                <\/a>\n                            <\/h3>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/hr\/brand\/se-doll\/\" title=\"SE Lutka\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-se.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-se.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-se-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-se-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-se-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <h3>\n                                <a href=\"https:\/\/renodoll.com\/hr\/brand\/starpery-doll\/\" title=\"View all products from Starpery Doll\">\n\t\t\t\t\t\t\t\t\tStarpery Doll                                <\/a>\n                            <\/h3>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <h3>\n                                <a href=\"https:\/\/renodoll.com\/hr\/brand\/sweet-doll\/\" title=\"View all products from Sweet Doll\">\n\t\t\t\t\t\t\t\t\tSweet Doll                                <\/a>\n                            <\/h3>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <h3>\n                                <a href=\"https:\/\/renodoll.com\/hr\/brand\/top-fire-doll\/\" title=\"View all products from Top Fire Doll\">\n\t\t\t\t\t\t\t\t\tTop Fire Doll                                <\/a>\n                            <\/h3>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/hr\/brand\/wm-doll\/\" title=\"WM lutka\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-wm.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-wm.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-wm-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-wm-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-wm-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <h3>\n                                <a href=\"https:\/\/renodoll.com\/hr\/brand\/xt-doll\/\" title=\"View all products from XT Doll\">\n\t\t\t\t\t\t\t\t\tXT Doll                                <\/a>\n                            <\/h3>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/hr\/brand\/yl-doll\/\" title=\"YL lutka\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-yl.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-yl.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-yl-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-yl-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/10\/logo-yl-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                            <div class=\"swiper-slide\">\n\n                            <div class=\"categories-mask\">\n\n\t\t\t\t\t\t\t\n                            <a href=\"https:\/\/renodoll.com\/hr\/brand\/zelex-doll\/\" title=\"Lutka Zelex\">\n\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renodoll.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" data-src=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-zelex.jpg\" class=\"lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" data-srcset=\"https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-zelex.jpg 150w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-zelex-12x12.jpg 12w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-zelex-100x100.jpg 100w, https:\/\/renodoll.com\/wp-content\/uploads\/2023\/04\/logo-zelex-10x10.jpg 10w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/>\n                            <\/a>\n\n\t\t\t\t\t\t\n                            <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t\n                    <\/div>\n\t\t\t\t\t\n                <\/div>\n\n\t\t\t\t\n                    <div class=\"swiper-button-prev swiper-custom-left swiper-nav et-swiper-elementor-nav type-arrow style-2\"><\/div>\n                    <div class=\"swiper-button-next swiper-custom-right swiper-nav et-swiper-elementor-nav type-arrow style-2\"><\/div>\n\n\t\t\t\t\t\t\t\t\t            <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Galerija lutki Dimenzije lutke Materijal TPE Visina 165 cm Neto te\u017eina 43 kg Poprsje 85 cm Struk 70 cm Kuk 90 cm Ruka 72 cm Rame 42 cm Du\u017eina noge 95 cm Dubina stopala 23 cm Dubina usne \u0161upljine 12 cm Dubina anusa 20 cm Meki penis 8 cm (duljina) * 4 cm (okrug) Tvrdi penis 16 cm (duljina th) *4,5 cm (okrug) Vi\u0161e informacija o lutki<\/p>","protected":false},"featured_media":63038,"comment_status":"open","ping_status":"closed","template":"","meta":[],"etheme_brands":[{"term_id":98,"name":"DH Doll","slug":"dh-doll","term_group":0,"term_taxonomy_id":98,"taxonomy":"brand","description":"","parent":0,"count":28,"filter":"raw"}],"product_brand":[],"product_cat":[65,70,47,53],"product_tag":[],"class_list":{"0":"post-58514","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"brand-dh-doll","7":"product_cat-160cm-169cm","8":"product_cat-male-love-doll","9":"product_cat-male-sex-doll","10":"product_cat-tpe-sex-doll","11":"tm-has-options","13":"first","14":"instock","15":"sale","16":"shipping-taxable","17":"purchasable","18":"product-type-simple"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/renodoll.com\/hr\/wp-json\/wp\/v2\/product\/58514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/renodoll.com\/hr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/renodoll.com\/hr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/renodoll.com\/hr\/wp-json\/wp\/v2\/comments?post=58514"}],"version-history":[{"count":1,"href":"https:\/\/renodoll.com\/hr\/wp-json\/wp\/v2\/product\/58514\/revisions"}],"predecessor-version":[{"id":58555,"href":"https:\/\/renodoll.com\/hr\/wp-json\/wp\/v2\/product\/58514\/revisions\/58555"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/renodoll.com\/hr\/wp-json\/wp\/v2\/media\/63038"}],"wp:attachment":[{"href":"https:\/\/renodoll.com\/hr\/wp-json\/wp\/v2\/media?parent=58514"}],"wp:term":[{"taxonomy":"brand","embeddable":true,"href":"https:\/\/renodoll.com\/hr\/wp-json\/wp\/v2\/etheme_brands?post=58514"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/renodoll.com\/hr\/wp-json\/wp\/v2\/product_brand?post=58514"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/renodoll.com\/hr\/wp-json\/wp\/v2\/product_cat?post=58514"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/renodoll.com\/hr\/wp-json\/wp\/v2\/product_tag?post=58514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}