{"id":86,"count":22,"description":"","link":"https:\/\/renodoll.com\/fi\/collections\/130cm-139cm\/","name":"130cm-139cm","slug":"130cm-139cm","taxonomy":"product_cat","parent":0,"meta":{"order":["0"],"product_count_product_cat":["21"],"_trp_automatically_translated_slug_es_ES":["130cm-139cm"],"_trp_automatically_translated_slug_fr_FR":["130-cm-139-cm"],"_trp_automatically_translated_slug_de_DE":["130cm-139cm"],"_trp_automatically_translated_slug_it_IT":["130-cm-139-cm"],"_trp_automatically_translated_slug_nl_NL":["130cm-139cm"],"_trp_automatically_translated_slug_et":["130-139-cm"],"_trp_automatically_translated_slug_hu_HU":["130-139-cm"],"_trp_automatically_translated_slug_el":["130cm-139cm"],"_trp_automatically_translated_slug_bg_BG":["130%d1%81%d0%bc-139%d1%81%d0%bc"],"_trp_automatically_translated_slug_lt_LT":["130-139-cm"],"_trp_automatically_translated_slug_fi":["130-139-cm"],"_trp_automatically_translated_slug_sv_SE":["130-139-cm"],"_trp_automatically_translated_slug_da_DK":["130-139-cm"],"_trp_automatically_translated_slug_pt_PT":["130cm-139cm"],"_trp_automatically_translated_slug_pl_PL":["130-cm-139-cm"],"_trp_automatically_translated_slug_cs_CZ":["130-139-cm"],"_trp_automatically_translated_slug_hr":["130cm-139cm"],"_trp_automatically_translated_slug_sl_SI":["130cm-139cm"],"_trp_automatically_translated_slug_lv":["130-139-cm"],"_trp_automatically_translated_slug_nb_NO":["130-139-cm"],"_trp_automatically_translated_slug_ro_RO":["130cm-139cm"],"_trp_automatically_translated_slug_sk_SK":["130-139-cm"]},"menu_order":0,"_links":{"self":[{"href":"https:\/\/renodoll.com\/fi\/wp-json\/wp\/v2\/product_cat\/86","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/renodoll.com\/fi\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/renodoll.com\/fi\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/renodoll.com\/fi\/wp-json\/wp\/v2\/product?product_cat=86"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}