{"id":108,"count":10,"description":"","link":"https:\/\/renodoll.com\/cs\/collections\/diy-sex-doll\/","name":"DIY Sex Doll","slug":"diy-sex-doll","taxonomy":"product_cat","parent":0,"meta":{"order":["0"],"display_type":[""],"thumbnail_id":["0"],"product_count_product_cat":["10"],"_trp_automatically_translated_slug_cs_CZ":["diy-sexualni-panenka"],"_trp_automatically_translated_slug_nb_NO":["gjor-det-selv-sexdukke"],"_trp_automatically_translated_slug_lv":["pasdarinata-seksa-lelle"],"_trp_automatically_translated_slug_pl_PL":["lalka-seks-zrob-to-sam"],"_trp_automatically_translated_slug_lt_LT":["pasidaryk-pats-sekso-lele"],"_trp_automatically_translated_slug_da_DK":["gor-det-selv-sexdukke"],"_trp_automatically_translated_slug_et":["isetehtud-seksinukk"],"_trp_automatically_translated_slug_sl_SI":["diy-seks-lutka"],"_trp_automatically_translated_slug_ro_RO":["papusa-sexuala-diy"],"_trp_automatically_translated_slug_pt_PT":["boneca-sexual-faca-voce-mesmo"],"_trp_automatically_translated_slug_de_DE":["diy-sexpuppe"],"_trp_automatically_translated_slug_it_IT":["bambola-del-sesso-fai-da-te"],"_trp_automatically_translated_slug_hr":["diy-lutka-za-seks"],"_trp_automatically_translated_slug_nl_NL":["zelfgemaakte-sekspop"],"_trp_automatically_translated_slug_hu_HU":["szexbaba-barkacsolashoz"],"_trp_automatically_translated_slug_bg_BG":["%d0%bd%d0%b0%d0%bf%d1%80%d0%b0%d0%b2%d0%b8-%d1%81%d0%b8-%d1%81%d0%b0%d0%bc-%d1%81%d0%b5%d0%ba%d1%81-%d0%ba%d1%83%d0%ba%d0%bb%d0%b0"],"_trp_automatically_translated_slug_el":["%ce%ba%ce%bf%cf%8d%ce%ba%ce%bb%ce%b1-%ce%b3%ce%b9%ce%b1-%cf%83%ce%b5%ce%be-%cf%83%ce%b5%ce%be"],"_trp_automatically_translated_slug_sv_SE":["gor-det-sjalv-sexdocka"],"_trp_automatically_translated_slug_fi":["tee-se-itse-seksinukke"],"_trp_automatically_translated_slug_sk_SK":["svojpomocna-sexualna-babika"],"_trp_automatically_translated_slug_es_ES":["muneca-sexual-casera"],"_trp_automatically_translated_slug_fr_FR":["poupee-sexuelle-a-faire-soi-meme"]},"menu_order":0,"_links":{"self":[{"href":"https:\/\/renodoll.com\/cs\/wp-json\/wp\/v2\/product_cat\/108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/renodoll.com\/cs\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/renodoll.com\/cs\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/renodoll.com\/cs\/wp-json\/wp\/v2\/product?product_cat=108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}